{"id":126194,"date":"2025-12-12T03:47:55","date_gmt":"2025-12-12T02:47:55","guid":{"rendered":"https:\/\/www.lecourt-clermont.org\/film\/only-tenderness-en\/"},"modified":"2026-01-25T17:09:45","modified_gmt":"2026-01-25T16:09:45","slug":"only-tenderness-en","status":"publish","type":"film","link":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/","title":{"rendered":"Only Tenderness"},"content":{"rendered":"","protected":false},"featured_media":229820,"menu_order":0,"template":"","meta":{"_acf_changed":false},"genre":[176],"pays":[],"class_list":["post-126194","film","type-film","status-publish","has-post-thumbnail","hentry","genre-fiction"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Only Tenderness - Festival international du court-m\u00e9trage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Only Tenderness - Festival international du court-m\u00e9trage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Festival international du court-m\u00e9trage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T16:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/\",\"url\":\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/\",\"name\":\"Only Tenderness - Festival international du court-m\u00e9trage\",\"isPartOf\":{\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg\",\"datePublished\":\"2025-12-12T02:47:55+00:00\",\"dateModified\":\"2026-01-25T16:09:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#primaryimage\",\"url\":\"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg\",\"contentUrl\":\"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lecourt-clermont.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Only Tenderness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/#website\",\"url\":\"https:\/\/www.lecourt-clermont.org\/en\/\",\"name\":\"Festival international du court-m\u00e9trage\",\"description\":\"Le slogan du site\",\"publisher\":{\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lecourt-clermont.org\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/#organization\",\"name\":\"Festival international du court-m\u00e9trage\",\"url\":\"https:\/\/www.lecourt-clermont.org\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lecourt.cloud-sak.com\/wp-content\/uploads\/2024\/11\/SQP_Logo.png\",\"contentUrl\":\"https:\/\/lecourt.cloud-sak.com\/wp-content\/uploads\/2024\/11\/SQP_Logo.png\",\"width\":616,\"height\":470,\"caption\":\"Festival international du court-m\u00e9trage\"},\"image\":{\"@id\":\"https:\/\/www.lecourt-clermont.org\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Only Tenderness - Festival international du court-m\u00e9trage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/","og_locale":"en_US","og_type":"article","og_title":"Only Tenderness - Festival international du court-m\u00e9trage","og_url":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/","og_site_name":"Festival international du court-m\u00e9trage","article_modified_time":"2026-01-25T16:09:45+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/","url":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/","name":"Only Tenderness - Festival international du court-m\u00e9trage","isPartOf":{"@id":"https:\/\/www.lecourt-clermont.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#primaryimage"},"image":{"@id":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg","datePublished":"2025-12-12T02:47:55+00:00","dateModified":"2026-01-25T16:09:45+00:00","breadcrumb":{"@id":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#primaryimage","url":"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg","contentUrl":"https:\/\/www.lecourt-clermont.org\/wp-content\/uploads\/2026\/01\/film_200149285_2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.lecourt-clermont.org\/en\/movie\/only-tenderness-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lecourt-clermont.org\/en\/"},{"@type":"ListItem","position":2,"name":"Only Tenderness"}]},{"@type":"WebSite","@id":"https:\/\/www.lecourt-clermont.org\/en\/#website","url":"https:\/\/www.lecourt-clermont.org\/en\/","name":"Festival international du court-m\u00e9trage","description":"Le slogan du site","publisher":{"@id":"https:\/\/www.lecourt-clermont.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lecourt-clermont.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lecourt-clermont.org\/en\/#organization","name":"Festival international du court-m\u00e9trage","url":"https:\/\/www.lecourt-clermont.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lecourt-clermont.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lecourt.cloud-sak.com\/wp-content\/uploads\/2024\/11\/SQP_Logo.png","contentUrl":"https:\/\/lecourt.cloud-sak.com\/wp-content\/uploads\/2024\/11\/SQP_Logo.png","width":616,"height":470,"caption":"Festival international du court-m\u00e9trage"},"image":{"@id":"https:\/\/www.lecourt-clermont.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lecourt-clermont.org\/en\/wp-json\/wp\/v2\/film\/126194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lecourt-clermont.org\/en\/wp-json\/wp\/v2\/film"}],"about":[{"href":"https:\/\/www.lecourt-clermont.org\/en\/wp-json\/wp\/v2\/types\/film"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lecourt-clermont.org\/en\/wp-json\/wp\/v2\/media\/229820"}],"wp:attachment":[{"href":"https:\/\/www.lecourt-clermont.org\/en\/wp-json\/wp\/v2\/media?parent=126194"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.lecourt-clermont.org\/en\/wp-json\/wp\/v2\/genre?post=126194"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.lecourt-clermont.org\/en\/wp-json\/wp\/v2\/pays?post=126194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}